{"id":69259,"date":"2025-11-08T15:37:28","date_gmt":"2025-11-08T20:37:28","guid":{"rendered":"https:\/\/tudrogueriaenlinea.com\/?post_type=product&#038;p=69259"},"modified":"2025-11-08T15:37:40","modified_gmt":"2025-11-08T20:37:40","slug":"neurozin-syrup-2-botellas-100-mld","status":"publish","type":"product","link":"https:\/\/tudrogueriaenlinea.com\/index.php\/product\/neurozin-syrup-2-botellas-100-mld\/","title":{"rendered":"NEUROZIN SYRUP 2 BOTELLAS 100 ML(D)"},"content":{"rendered":"<p>Este producto se encuentra actualmente descontinuado o sin disponibilidad en nuestro cat\u00e1logo.<\/p>\n<p>Si necesitas asesor\u00eda para encontrar una alternativa equivalente o apoyo en la consecuci\u00f3n del medicamento que requieres, nuestro equipo est\u00e1 listo para ayudarte.<\/p>\n<p>Cont\u00e1ctanos a trav\u00e9s de WhatsApp al +57 313 209 1915 o escr\u00edbenos a contacto@tudrogueriaenlinea.com.<\/p>\n<p>Ser\u00e1 un gusto acompa\u00f1arte en tu proceso de compra y brindarte la orientaci\u00f3n necesaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este producto se encuentra actualmente descontinuado o sin disponibilidad en nuestro cat\u00e1logo.<\/p>\n<p>Si necesitas asesor\u00eda para encontrar una alternativa equivalente o apoyo en la consecuci\u00f3n del medicamento que requieres, nuestro equipo est\u00e1 listo para ayudarte.<\/p>\n<p>Cont\u00e1ctanos a trav\u00e9s de WhatsApp al +57 313 209 1915 o escr\u00edbenos a contacto@tudrogueriaenlinea.com.<\/p>\n<p>Ser\u00e1 un gusto acompa\u00f1arte en tu proceso de compra y brindarte la orientaci\u00f3n necesaria.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"product_brand":[20438],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-69259","1":"product","2":"type-product","3":"status-publish","5":"product_brand-rigel-laboratorios-s-a-s","6":"product_cat-uncategorized","7":"post","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product\/69259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/media?parent=69259"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=69259"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=69259"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=69259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}