{"id":79244,"date":"2025-11-09T12:55:34","date_gmt":"2025-11-09T17:55:34","guid":{"rendered":"https:\/\/tudrogueriaenlinea.com\/?post_type=product&#038;p=79244"},"modified":"2025-11-09T12:55:47","modified_gmt":"2025-11-09T17:55:47","slug":"quinidurina-200-mg-30-tbs-epsd","status":"publish","type":"product","link":"https:\/\/tudrogueriaenlinea.com\/index.php\/product\/quinidurina-200-mg-30-tbs-epsd\/","title":{"rendered":"QUINIDURINA 200 MG 30 TBS # EPS(D)"},"content":{"rendered":"<p>Este producto se encuentra actualmente descontinuado o sin disponibilidad en nuestro cat\u00e1logo.<\/p>\n<p>Si necesitas asesor\u00eda para encontrar una alternativa equivalente o apoyo en la consecuci\u00f3n del medicamento que requieres, nuestro equipo est\u00e1 listo para ayudarte.<\/p>\n<p>Cont\u00e1ctanos a trav\u00e9s de WhatsApp al +57 313 209 1915 o escr\u00edbenos a contacto@tudrogueriaenlinea.com.<\/p>\n<p>Ser\u00e1 un gusto acompa\u00f1arte en tu proceso de compra y brindarte la orientaci\u00f3n necesaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este producto se encuentra actualmente descontinuado o sin disponibilidad en nuestro cat\u00e1logo.<\/p>\n<p>Si necesitas asesor\u00eda para encontrar una alternativa equivalente o apoyo en la consecuci\u00f3n del medicamento que requieres, nuestro equipo est\u00e1 listo para ayudarte.<\/p>\n<p>Cont\u00e1ctanos a trav\u00e9s de WhatsApp al +57 313 209 1915 o escr\u00edbenos a contacto@tudrogueriaenlinea.com.<\/p>\n<p>Ser\u00e1 un gusto acompa\u00f1arte en tu proceso de compra y brindarte la orientaci\u00f3n necesaria.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"product_brand":[2933],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-79244","1":"product","2":"type-product","3":"status-publish","5":"product_brand-ropsohn-therapeutics","6":"product_cat-uncategorized","7":"post","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product\/79244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/media?parent=79244"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=79244"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=79244"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tudrogueriaenlinea.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=79244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}